{"id":2403,"date":"2025-10-30T09:38:35","date_gmt":"2025-10-30T12:38:35","guid":{"rendered":"https:\/\/www.fecomercio-ce.com.br\/sescce\/?page_id=2403"},"modified":"2026-04-30T14:12:11","modified_gmt":"2026-04-30T17:12:11","slug":"espaco-artesao","status":"publish","type":"page","link":"https:\/\/www.fecomercio-ce.com.br\/sescce\/espaco-artesao\/","title":{"rendered":"Espa\u00e7o Artes\u00e3o"},"content":{"rendered":"<p><strong>No Espa\u00e7o Artes\u00e3o, cada pe\u00e7a conta uma hist\u00f3ria,<br \/>\nexpressando a tradi\u00e7\u00e3o e a criatividade dos nossos talentosos artes\u00e3os.<\/strong><\/p>\n<p>Ao escolher um de nossos produtos, voc\u00ea fortalece a cultura local e apoia quem transforma arte em legado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No Espa\u00e7o Artes\u00e3o, cada pe\u00e7a conta uma hist\u00f3ria, expressando a tradi\u00e7\u00e3o e a criatividade dos nossos talentosos artes\u00e3os. Ao escolher um de nossos produtos, voc\u00ea fortalece a cultura local e apoia quem transforma arte em legado.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-lp.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2403","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Espa\u00e7o Artes\u00e3o - Sesc Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fecomercio-ce.com.br\/sescce\/espaco-artesao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Espa\u00e7o Artes\u00e3o - Sesc Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"No Espa\u00e7o Artes\u00e3o, cada pe\u00e7a conta uma hist\u00f3ria, expressando a tradi\u00e7\u00e3o e a criatividade dos nossos talentosos artes\u00e3os. Ao escolher um de nossos produtos, voc\u00ea fortalece a cultura local e apoia quem transforma arte em legado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fecomercio-ce.com.br\/sescce\/espaco-artesao\/\" \/>\n<meta property=\"og:site_name\" content=\"Sesc Cear\u00e1\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-30T17:12:11+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fecomercio-ce.com.br\/sescce\/espaco-artesao\/\",\"url\":\"https:\/\/www.fecomercio-ce.com.br\/sescce\/espaco-artesao\/\",\"name\":\"Espa\u00e7o Artes\u00e3o - Sesc Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/www.fecomercio-ce.com.br\/sescce\/#website\"},\"datePublished\":\"2025-10-30T12:38:35+00:00\",\"dateModified\":\"2026-04-30T17:12:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fecomercio-ce.com.br\/sescce\/espaco-artesao\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fecomercio-ce.com.br\/sescce\/espaco-artesao\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fecomercio-ce.com.br\/sescce\/espaco-artesao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.fecomercio-ce.com.br\/sescce\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Espa\u00e7o Artes\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fecomercio-ce.com.br\/sescce\/#website\",\"url\":\"https:\/\/www.fecomercio-ce.com.br\/sescce\/\",\"name\":\"Sesc Cear\u00e1\",\"description\":\"O Servi\u00e7o Social do Com\u00e9rcio (Sesc), bra\u00e7o social do Sistema Fecom\u00e9rcio-CE. Atua nas \u00e1reas de Educa\u00e7\u00e3o, Cultura, Lazer, Sa\u00fade e Assist\u00eancia.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fecomercio-ce.com.br\/sescce\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Espa\u00e7o Artes\u00e3o - Sesc Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fecomercio-ce.com.br\/sescce\/espaco-artesao\/","og_locale":"pt_BR","og_type":"article","og_title":"Espa\u00e7o Artes\u00e3o - Sesc Cear\u00e1","og_description":"No Espa\u00e7o Artes\u00e3o, cada pe\u00e7a conta uma hist\u00f3ria, expressando a tradi\u00e7\u00e3o e a criatividade dos nossos talentosos artes\u00e3os. Ao escolher um de nossos produtos, voc\u00ea fortalece a cultura local e apoia quem transforma arte em legado.","og_url":"https:\/\/www.fecomercio-ce.com.br\/sescce\/espaco-artesao\/","og_site_name":"Sesc Cear\u00e1","article_modified_time":"2026-04-30T17:12:11+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fecomercio-ce.com.br\/sescce\/espaco-artesao\/","url":"https:\/\/www.fecomercio-ce.com.br\/sescce\/espaco-artesao\/","name":"Espa\u00e7o Artes\u00e3o - Sesc Cear\u00e1","isPartOf":{"@id":"https:\/\/www.fecomercio-ce.com.br\/sescce\/#website"},"datePublished":"2025-10-30T12:38:35+00:00","dateModified":"2026-04-30T17:12:11+00:00","breadcrumb":{"@id":"https:\/\/www.fecomercio-ce.com.br\/sescce\/espaco-artesao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fecomercio-ce.com.br\/sescce\/espaco-artesao\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fecomercio-ce.com.br\/sescce\/espaco-artesao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.fecomercio-ce.com.br\/sescce\/"},{"@type":"ListItem","position":2,"name":"Espa\u00e7o Artes\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/www.fecomercio-ce.com.br\/sescce\/#website","url":"https:\/\/www.fecomercio-ce.com.br\/sescce\/","name":"Sesc Cear\u00e1","description":"O Servi\u00e7o Social do Com\u00e9rcio (Sesc), bra\u00e7o social do Sistema Fecom\u00e9rcio-CE. Atua nas \u00e1reas de Educa\u00e7\u00e3o, Cultura, Lazer, Sa\u00fade e Assist\u00eancia.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fecomercio-ce.com.br\/sescce\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/www.fecomercio-ce.com.br\/sescce\/wp-json\/wp\/v2\/pages\/2403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fecomercio-ce.com.br\/sescce\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fecomercio-ce.com.br\/sescce\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fecomercio-ce.com.br\/sescce\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fecomercio-ce.com.br\/sescce\/wp-json\/wp\/v2\/comments?post=2403"}],"version-history":[{"count":17,"href":"https:\/\/www.fecomercio-ce.com.br\/sescce\/wp-json\/wp\/v2\/pages\/2403\/revisions"}],"predecessor-version":[{"id":4679,"href":"https:\/\/www.fecomercio-ce.com.br\/sescce\/wp-json\/wp\/v2\/pages\/2403\/revisions\/4679"}],"wp:attachment":[{"href":"https:\/\/www.fecomercio-ce.com.br\/sescce\/wp-json\/wp\/v2\/media?parent=2403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}